{"id":1552,"date":"2014-03-18T18:41:03","date_gmt":"2014-03-18T18:41:03","guid":{"rendered":"http:\/\/municipalidadalhue.cl\/portal\/?p=1552"},"modified":"2014-03-19T14:12:22","modified_gmt":"2014-03-19T14:12:22","slug":"se-supervisaron-proyectos-en-utilizacion-de-energia-solar-y-acumuladores-de-aguas-lluvias","status":"publish","type":"post","link":"https:\/\/municipalidadalhue.cl\/portal\/se-supervisaron-proyectos-en-utilizacion-de-energia-solar-y-acumuladores-de-aguas-lluvias\/","title":{"rendered":"Se supervisaron proyectos en utilizaci\u00f3n de energ\u00eda solar y acumuladores de aguas lluvias"},"content":{"rendered":"<p><b>El M\u00f3dulo II de PRODESAL inspeccion\u00f3 los avances de estas iniciativas en los sectores de Hacienda y Villa Alhu\u00e9, constatando el adecuado funcionamiento de cada uno.<\/b><\/p>\n<p><a href=\"http:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/03\/20140227_152014.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignright size-medium wp-image-1553\" alt=\"20140227_152014\" src=\"http:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/03\/20140227_152014-300x260.jpg\" width=\"300\" height=\"260\" srcset=\"https:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/03\/20140227_152014-300x260.jpg 300w, https:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/03\/20140227_152014-1024x888.jpg 1024w, https:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/03\/20140227_152014-900x780.jpg 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Entre enero y febrero de este a\u00f1o la oficina de PRODESAL (Programa de Desarrollo Local) supervis\u00f3 el funcionamiento de una serie de proyectos enmarcados en el uso de energ\u00eda solar, adem\u00e1s de la utilizaci\u00f3n de acumuladores de aguas lluvias.<\/p>\n<p>Los profesionales que son parte del M\u00f3dulo II de esta oficina realizaron estas inspecciones a cerca de 14 agricultores pertenecientes a las localidades de Hacienda y Villa Alhu\u00e9.<\/p>\n<p>El jefe t\u00e9cnico de este M\u00f3dulo, Mario Pinz\u00f3n, recalc\u00f3 que \u201csupervisamos la instalaci\u00f3n y el uso de los paneles solares que ayudar\u00e1n a nuestros usuarios, y tambi\u00e9n revisamos el funcionamiento de los equipos de bombeo de conversi\u00f3n de energ\u00eda solar\u201d.<\/p>\n<p>Es de esperar que los beneficiarios PRODESAL aprovechen de la mejor forma esta implementaci\u00f3n que se les otorg\u00f3, para que sigan desarroll\u00e1ndose por el bien de sus familias.\u00a0<b><\/b><\/p>\n<p>Vea la galer\u00eda de im\u00e1genes en nuestro facebook:<\/p>\n<p><a href=\"http:\/\/www.facebook.com\/pages\/Ilustre-Municipalidad-de-Alhu%C3%A9\/208816755829101\">http:\/\/www.facebook.com\/pages\/Ilustre-Municipalidad-de-Alhu%C3%A9\/208816755829101<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El M\u00f3dulo II de PRODESAL inspeccion\u00f3 los avances de estas iniciativas en los sectores de Hacienda y Villa Alhu\u00e9, constatando el adecuado funcionamiento de cada uno. Entre enero y febrero de este a\u00f1o la oficina de PRODESAL (Programa de Desarrollo Local) supervis\u00f3 el funcionamiento de una serie de proyectos enmarcados en el uso de energ\u00eda solar, adem\u00e1s de la utilizaci\u00f3n de acumuladores de aguas lluvias. Los profesionales que son parte del M\u00f3dulo II de esta oficina realizaron estas inspecciones a cerca de 14 agricultores pertenecientes a las localidades de Hacienda&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1552","post","type-post","status-publish","format-standard","hentry","category-noticia"],"_links":{"self":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/posts\/1552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/comments?post=1552"}],"version-history":[{"count":0,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/posts\/1552\/revisions"}],"wp:attachment":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/media?parent=1552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/categories?post=1552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/tags?post=1552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}