{"id":1609,"date":"2014-04-01T15:46:42","date_gmt":"2014-04-01T15:46:42","guid":{"rendered":"http:\/\/municipalidadalhue.cl\/portal\/?p=1609"},"modified":"2014-04-07T14:06:11","modified_gmt":"2014-04-07T14:06:11","slug":"oficina-de-la-infacia-finalizo-actividades-2013","status":"publish","type":"post","link":"https:\/\/municipalidadalhue.cl\/portal\/oficina-de-la-infacia-finalizo-actividades-2013\/","title":{"rendered":"Oficina de la Infancia finaliz\u00f3 actividades 2013"},"content":{"rendered":"<p><b>Desde la Casa de la Cultura se realiz\u00f3 la entrega de una serie de est\u00edmulos a los ni\u00f1os que participaron de las diferentes presentaciones que realizaron durante el a\u00f1o pasado, culminando con la obertura que efectuaron en la Semana Alhu\u00edna 2014. Todos los ni\u00f1os que quieran participar de esta iniciativa deben dirigirse a DIDECO, en nuestro municipio.<\/b><\/p>\n<p><a href=\"http:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/04\/DSC03948.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignright size-medium wp-image-1610\" alt=\"DSC03948\" src=\"http:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/04\/DSC03948-300x221.jpg\" width=\"300\" height=\"221\" srcset=\"https:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/04\/DSC03948-300x221.jpg 300w, https:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/04\/DSC03948-1024x757.jpg 1024w, https:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/04\/DSC03948-900x665.jpg 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>La gesti\u00f3n del Alcalde Roberto Torres Huerta se ha preocupado constantemente de los ni\u00f1os, ya que son un pilar fundamental en el desarrollo de su administraci\u00f3n. Por ello, fomentar las actividades de la Oficina de la Infancia de DIDECO (Direcci\u00f3n de Desarrollo Comunitario) es primordial.<\/p>\n<p>En ese sentido, el 31 de marzo esta oficina realiz\u00f3 el cierre del ciclo 2013, con una premiaci\u00f3n para todos los ni\u00f1os que participaron de las diversas presentaciones que desarrollaron en este periodo.<\/p>\n<p>\u201cPremiamos a los ni\u00f1os que participaron del taller de danza creativa, quienes ofrecieron hermosas presentaciones durante el a\u00f1o, cerrando con la obertura que ofrecieron en la Semana Alhu\u00edna\u201d, explic\u00f3 Isabel Rivera, encargada de la Oficina de la Infancia, Isabel Rivera.<\/p>\n<p>Asimismo, indic\u00f3 que algunos de los ni\u00f1os que son parte de la agrupaci\u00f3n \u201cSemillitas\u201d se retirar\u00e1n, dando paso a los \u201cCapullitos\u201d, los que desde el 2014 se integrar\u00e1n a esta oficina.<\/p>\n<p>Todos los ni\u00f1os de 4 a 14 a\u00f1os que quieran ser parte de esta iniciativa, deben dirigirse hasta DIDECO y hablar con la encargada, quien los inscribir\u00e1 para participar de los diferentes talleres que ofrecer\u00e1n durante este a\u00f1o, los que se desarrollar\u00e1n en la Casa de la Cultura de Villa Alhu\u00e9, desde las 16:00 horas.<\/p>\n<p>\u201cHabr\u00e1n talleres de pintura, de danza, de cuidado ambiental, centrado en el reciclaje. Adem\u00e1s, ofreceremos charlas para los padres y fomentaremos la lectura en los ni\u00f1os con la hora del cuento\u201d, destac\u00f3 Rivera.<\/p>\n<p>Se debe destacar, que tambi\u00e9n invitar\u00e1n a diversos cursos del Liceo Sara Troncoso, para seguir incentivando la lectura con ellos. \u201cTraeremos a alumnos de kinder, primero y segundo B\u00e1sico, para que tambi\u00e9n puedan desarrollar sus habilidades en lenguaje\u201d, cerr\u00f3.<\/p>\n<p>Vea la galer\u00eda de im\u00e1genes en nuestro facebook:<\/p>\n<p><a href=\"http:\/\/www.facebook.com\/pages\/Ilustre-Municipalidad-de-Alhu%C3%A9\/208816755829101\">http:\/\/www.facebook.com\/pages\/Ilustre-Municipalidad-de-Alhu%C3%A9\/208816755829101<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde la Casa de la Cultura se realiz\u00f3 la entrega de una serie de est\u00edmulos a los ni\u00f1os que participaron de las diferentes presentaciones que realizaron durante el a\u00f1o pasado, culminando con la obertura que efectuaron en la Semana Alhu\u00edna 2014. Todos los ni\u00f1os que quieran participar de esta iniciativa deben dirigirse a DIDECO, en nuestro municipio. La gesti\u00f3n del Alcalde Roberto Torres Huerta se ha preocupado constantemente de los ni\u00f1os, ya que son un pilar fundamental en el desarrollo de su administraci\u00f3n. Por ello, fomentar las actividades de la&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1609","post","type-post","status-publish","format-standard","hentry","category-noticia"],"_links":{"self":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/posts\/1609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/comments?post=1609"}],"version-history":[{"count":0,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/posts\/1609\/revisions"}],"wp:attachment":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/media?parent=1609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/categories?post=1609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/tags?post=1609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}