{"id":1822,"date":"2014-05-14T16:57:01","date_gmt":"2014-05-14T16:57:01","guid":{"rendered":"http:\/\/municipalidadalhue.cl\/portal\/?p=1822"},"modified":"2014-05-19T15:13:28","modified_gmt":"2014-05-19T15:13:28","slug":"sercotec-desarrollo-capacitacion-para-emprendedoras-de-alhue","status":"publish","type":"post","link":"https:\/\/municipalidadalhue.cl\/portal\/sercotec-desarrollo-capacitacion-para-emprendedoras-de-alhue\/","title":{"rendered":"SERCOTEC desarroll\u00f3 capacitaci\u00f3n para emprendedoras de Alhu\u00e9"},"content":{"rendered":"<p><b>Profesionales del Servicio de Cooperaci\u00f3n T\u00e9cnica se dirigieron hasta nuestra comuna para instruir a vecinas en el programa Capital Abeja, fondo concursable que busca promover la creaci\u00f3n de nuevos negocios, como el fortalecimiento de los que est\u00e1n en etapa inicial.<\/b><\/p>\n<p><a href=\"http:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/05\/DSC04233.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignright size-medium wp-image-1823\" alt=\"DSC04233\" src=\"http:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/05\/DSC04233-300x188.jpg\" width=\"300\" height=\"188\" srcset=\"https:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/05\/DSC04233-300x188.jpg 300w, https:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/05\/DSC04233-1024x642.jpg 1024w, https:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/05\/DSC04233-900x564.jpg 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>El 13 de mayo funcionarios de SERCOTEC (Servicio de Cooperaci\u00f3n T\u00e9cnica) realizaron una capacitaci\u00f3n para las mujeres emprendedoras de nuestra comuna en la Sala de Sesiones de la Ilustre Municipalidad de Alhu\u00e9.<\/p>\n<p>El taller estuvo centrado en el programa Capital Abeja, fondo concursable que busca promover, tanto la creaci\u00f3n de nuevos negocios, como el fortalecimiento de aquellos que est\u00e1n en etapa inicial.<\/p>\n<p>\u201cLa idea principal de esta cita era fomentar e incentivar a las mujeres de la comuna para que postulen a este programa que est\u00e1 espec\u00edficamente orientado a las mujeres, buscando el desarrollo de negocios existentes o nuevos\u201d, explic\u00f3 Antonella Beneventi, ejecutiva de Fomento SERCOTEC.<\/p>\n<p>La profesional indic\u00f3 que esta iniciativa est\u00e1 dirigida a mujeres que s\u00f3lo cuentan con una idea de negocio y que requieren de un financiamiento inicial para concretar su idea, o bien, a mujeres empresarias que realicen una actividad econ\u00f3mica, pero que est\u00e9 en una etapa inicial y requieran de un financiamiento para consolidar esta actividad. \u201cEl subsidio que se les entrega a las ganadoras var\u00eda entre $500 mil y $1 mill\u00f3n 500 mil\u201d, expres\u00f3.<\/p>\n<p>Para poder postular a este programa las interesadas deben hacerlo a trav\u00e9s de Internet. \u201cDeben poseer un correo electr\u00f3nico, con \u00e9l deben registrarse en la p\u00e1gina www.sercotec.cl, para luego completar un test de diagn\u00f3stico, aprobando esa prueba, pueden postular con su plan de negocios. Si las personas que optaron tienen un puntaje suficiente para financiar su proyecto, resultan ganadoras, firmando un contrato con SERCOTEC\u201d, indic\u00f3 la profesional.<\/p>\n<p>Asimismo, Beneventi agrega que \u201cen ambos casos, cada emprendedora o empresaria, deber\u00e1 cofinanciar al menos el 20% sobre el aporte de SERCOTEC, en efectivo\u201d.<\/p>\n<p>Las Postulaciones para Capital Abeja l\u00ednea son desde el 9 al 23 de mayo. Cabe destacar, que los profesionales de Servicio Pa\u00eds que trabajan en nuestro municipio ofrecer\u00e1n apoyo en las postulaciones que hagan nuestras vecinas. Para mayor informaci\u00f3n contactarse a los siguientes correos electr\u00f3nicos: gladys.perez@serviciopais.cl, jose.castillo@serviciopais.cl, genesis.perez@serviciopais.cl.<\/p>\n<p>Vea la galer\u00eda de im\u00e1genes en nuestro facebook:<\/p>\n<p><a href=\"http:\/\/www.facebook.com\/pages\/Ilustre-Municipalidad-de-Alhu%C3%A9\/208816755829101\">http:\/\/www.facebook.com\/pages\/Ilustre-Municipalidad-de-Alhu%C3%A9\/208816755829101<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Profesionales del Servicio de Cooperaci\u00f3n T\u00e9cnica se dirigieron hasta nuestra comuna para instruir a vecinas en el programa Capital Abeja, fondo concursable que busca promover la creaci\u00f3n de nuevos negocios, como el fortalecimiento de los que est\u00e1n en etapa inicial. El 13 de mayo funcionarios de SERCOTEC (Servicio de Cooperaci\u00f3n T\u00e9cnica) realizaron una capacitaci\u00f3n para las mujeres emprendedoras de nuestra comuna en la Sala de Sesiones de la Ilustre Municipalidad de Alhu\u00e9. El taller estuvo centrado en el programa Capital Abeja, fondo concursable que busca promover, tanto la creaci\u00f3n de&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1822","post","type-post","status-publish","format-standard","hentry","category-noticia"],"_links":{"self":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/posts\/1822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/comments?post=1822"}],"version-history":[{"count":0,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/posts\/1822\/revisions"}],"wp:attachment":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/media?parent=1822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/categories?post=1822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/tags?post=1822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}