{"id":1947,"date":"2014-06-05T15:03:08","date_gmt":"2014-06-05T15:03:08","guid":{"rendered":"http:\/\/municipalidadalhue.cl\/portal\/?p=1947"},"modified":"2014-06-12T20:09:21","modified_gmt":"2014-06-12T20:09:21","slug":"se-estan-conformando-comites-de-vivienda-en-alhue","status":"publish","type":"post","link":"https:\/\/municipalidadalhue.cl\/portal\/se-estan-conformando-comites-de-vivienda-en-alhue\/","title":{"rendered":"Se est\u00e1n conformando Comit\u00e9s de Vivienda en Alhu\u00e9"},"content":{"rendered":"<p><b>Funcionarias del Departamento Social de nuestra comuna gestionaron la creaci\u00f3n de estas organizaciones que tienen el objetivo de entregar la anhelada casa propia a cerca de 80 familias.<\/b><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignright size-medium wp-image-1948\" alt=\"DSC04451\" src=\"http:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/06\/DSC04451-300x210.jpg\" width=\"300\" height=\"210\" srcset=\"https:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/06\/DSC04451-300x210.jpg 300w, https:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/06\/DSC04451-1024x716.jpg 1024w, https:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/06\/DSC04451-900x630.jpg 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Para acceder a un hogar es necesario realizar una serie de tr\u00e1mites que toman mucho tiempo, lo que se traduce en una espera que parece no terminar. Por ello, el Departamento Social a trav\u00e9s de la Oficina de la Vivienda organiz\u00f3 desde el 4 de junio una serie de reuniones para conformar Comit\u00e9s de Vivienda.<\/p>\n<p>La estudiante en pr\u00e1ctica de Trabajo Social, Victoria Viera, present\u00f3 este proyecto junto con la encargada de esta oficina municipal, Karina Moreno, quien destac\u00f3 que \u201cinvitamos a cerca de 60 personas a participar de este comit\u00e9, pero tuvimos una alta convocatoria, sobrepasando 80 vecinos. Tendremos que conformar dos comit\u00e9s, ya que son muchos los vecinos interesados\u201d.<\/p>\n<p>Asimismo, explica que \u201cel objetivo de estos comit\u00e9s es apoyar en el proceso de postulaci\u00f3n a la vivienda. Nosotros somos el puente entre el SERVIU y cada uno de los postulantes\u201d.<\/p>\n<p>Durante esta jornada se dieron a conocer los requisitos necesarios para ser parte del \u201cComit\u00e9 de Vivienda Esperanza e Ilusi\u00f3n\u201d. Los integrantes deben ser residentes de la comuna; tener la Ficha de Protecci\u00f3n Social vigente; ser mayor de 18 a\u00f1os; adem\u00e1s de poseer una carencia habitacional.<\/p>\n<p>Karina Moreno asever\u00f3 que pr\u00f3ximamente conformar\u00e1n los estatutos de esta organizaci\u00f3n, \u201cya que debe tener una personalidad jur\u00eddica este Comit\u00e9 de Vivienda\u201d, agreg\u00f3.<\/p>\n<p>La profesional recalc\u00f3 la alta participaci\u00f3n que tuvo esta cita. \u201cNo pens\u00e9 que iba a llegar tanta gente. Fue sorpresivo. Creo que este tipo de proyectos sirven para conocer las necesidades de la comunidad, porque as\u00ed podemos tomar las medidas que puedan satisfacer los requerimientos de la gente\u201d, indic\u00f3.<\/p>\n<p>Se debe destacar que pr\u00f3ximamente se reunir\u00e1 otro grupo de interesados en conformar un Comit\u00e9 de Vivienda, quienes tienen un solo objetivo: obtener la anhelada casa propia.<\/p>\n<p>Vea la galer\u00eda de im\u00e1genes en nuestro facebook:<\/p>\n<p><a href=\"http:\/\/www.facebook.com\/pages\/Ilustre-Municipalidad-de-Alhu%C3%A9\/208816755829101\">http:\/\/www.facebook.com\/pages\/Ilustre-Municipalidad-de-Alhu%C3%A9\/208816755829101<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Funcionarias del Departamento Social de nuestra comuna gestionaron la creaci\u00f3n de estas organizaciones que tienen el objetivo de entregar la anhelada casa propia a cerca de 80 familias. Para acceder a un hogar es necesario realizar una serie de tr\u00e1mites que toman mucho tiempo, lo que se traduce en una espera que parece no terminar. Por ello, el Departamento Social a trav\u00e9s de la Oficina de la Vivienda organiz\u00f3 desde el 4 de junio una serie de reuniones para conformar Comit\u00e9s de Vivienda. La estudiante en pr\u00e1ctica de Trabajo Social,&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,8],"tags":[],"class_list":["post-1947","post","type-post","status-publish","format-standard","hentry","category-comunidad","category-noticia"],"_links":{"self":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/posts\/1947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/comments?post=1947"}],"version-history":[{"count":0,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/posts\/1947\/revisions"}],"wp:attachment":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/media?parent=1947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/categories?post=1947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/tags?post=1947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}