{"id":2078,"date":"2014-06-11T18:32:02","date_gmt":"2014-06-11T18:32:02","guid":{"rendered":"http:\/\/municipalidadalhue.cl\/portal\/?p=2078"},"modified":"2014-06-16T12:44:25","modified_gmt":"2014-06-16T12:44:25","slug":"oficina-del-adulto-mayor-esta-ofreciendo-diversos-talleres-para-la-comunidad","status":"publish","type":"post","link":"https:\/\/municipalidadalhue.cl\/portal\/oficina-del-adulto-mayor-esta-ofreciendo-diversos-talleres-para-la-comunidad\/","title":{"rendered":"Oficina del Adulto Mayor est\u00e1 ofreciendo diversos talleres para la comunidad"},"content":{"rendered":"<p><b>Las personas de mayor experiencia de nuestra comuna podr\u00e1n participar de una serie de iniciativas, como son cursos b\u00e1sicos de computaci\u00f3n y de alfabetizaci\u00f3n, adem\u00e1s de jornadas de esparcimiento durante las reuniones que realiza cada Club de Adulto Mayor de Alhu\u00e9.<\/b><\/p>\n<p><a href=\"http:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/06\/DSC04169.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignright size-medium wp-image-2079\" alt=\"DSC04169\" src=\"http:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/06\/DSC04169-300x204.jpg\" width=\"300\" height=\"204\" srcset=\"https:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/06\/DSC04169-300x204.jpg 300w, https:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/06\/DSC04169-1024x699.jpg 1024w, https:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/06\/DSC04169-900x614.jpg 900w, https:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/06\/DSC04169.jpg 1037w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Los adultos mayores son un grupo etario muy importante para nuestro municipio, ya que con su sabidur\u00eda y experiencia, cada d\u00eda entregan mucho a la comuna. Por ello, la Oficina del Adulto Mayor de DIDECO est\u00e1 realizando una serie de talleres enfocados en su desarrollo.<\/p>\n<p>Desde principios de mayo se est\u00e1n ejecutando en la Biblioteca P\u00fablica cursos de computaci\u00f3n b\u00e1sica, para que las personas de mayor experiencia puedan hacerse parte del mundo virtual, utilizando Internet, entre otras herramientas.<\/p>\n<p>\u201cLas encargadas de la Biblioteca P\u00fablica est\u00e1n ofreciendo estos curso, porque\u00a0 queremos que los adultos mayores usen los computadores que est\u00e1n en la Uni\u00f3n Comunal de Adultos Mayores (UCAM), para que a trav\u00e9s de ellos puedan postular a diferentes proyectos, adem\u00e1s de utilizarlos para su bien personal\u201d, explic\u00f3 Guillermina N\u00fa\u00f1ez, encargada de esta oficina.<\/p>\n<p>Estos talleres se extender\u00e1n durante todo el a\u00f1o, realiz\u00e1ndose todas las semanas. Para poder participar de ellos, los interesados deben inscribirse en la Oficina del Adulto Mayor, ubicada en nuestro municipio.<\/p>\n<p>Asimismo, desde junio se est\u00e1n desarrollando talleres en cada una de las reuniones que realizan los diferentes Clubes de Adulto Mayor de la comuna, en donde la terapeuta ocupacional del Centro Comunitario de Rehabilitaci\u00f3n (CCR), Daniela Bustos, junto a Guillermina N\u00fa\u00f1ez, est\u00e1n capacitando a cada uno de los integrantes de estas organizaciones.<\/p>\n<p>Bustos est\u00e1 realizando el taller \u201cConociendo y viviendo nuestro envejecimiento\u201d, enfocado en alentar a los adultos mayores, para que puedan vivir de buena manera su vejez.<\/p>\n<p>El taller que realiza la encargada de la Oficina del Adulto Mayor es de \u201cAutocuidado\u201d, centrado en higiene personal, responsabilidad en el uso de medicamentos, adem\u00e1s de dar a conocer los diversos beneficios que les entrega el Estado.<\/p>\n<p>Por otra parte, a trav\u00e9s del Departamento de Educaci\u00f3n se realizar\u00e1n una serie de talleres de alfabetizaci\u00f3n, los que estar\u00e1n a cargo de la Coordinadora de la Unidad de Apoyo Financiero y Pedag\u00f3gico municipal, Carola Neira.<\/p>\n<p>Estos cursos se desarrollar\u00e1n dos veces por semana desde las sedes de cada Club de Adulto Mayor de Alhu\u00e9, en los que pueden participar cualquier interesado, y no necesariamente debe ser un adulto mayor. Las inscripciones se efectuar\u00e1n en esta misma oficina municipal. Pronto se informar\u00e1 el comienzo de estos talleres.<\/p>\n<p>En tanto, el 12 de mayo se realiz\u00f3 un operativo oftalmol\u00f3gico gratuito para todos los adultos mayores de nuestra comuna, a cargo de la \u00d3ptica CR de Melipilla.\u00a0Esta jornada se efectu\u00f3 en la sede de la UCAM, ubicada en calle Victoria, Villa Alhu\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las personas de mayor experiencia de nuestra comuna podr\u00e1n participar de una serie de iniciativas, como son cursos b\u00e1sicos de computaci\u00f3n y de alfabetizaci\u00f3n, adem\u00e1s de jornadas de esparcimiento durante las reuniones que realiza cada Club de Adulto Mayor de Alhu\u00e9. Los adultos mayores son un grupo etario muy importante para nuestro municipio, ya que con su sabidur\u00eda y experiencia, cada d\u00eda entregan mucho a la comuna. Por ello, la Oficina del Adulto Mayor de DIDECO est\u00e1 realizando una serie de talleres enfocados en su desarrollo. Desde principios de mayo&hellip;<\/p>\n","protected":false},"author":1,"featured_media":2081,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-2078","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia"],"_links":{"self":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/posts\/2078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/comments?post=2078"}],"version-history":[{"count":0,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/posts\/2078\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/media\/2081"}],"wp:attachment":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/media?parent=2078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/categories?post=2078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/tags?post=2078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}