{"id":2180,"date":"2014-06-30T20:49:32","date_gmt":"2014-06-30T20:49:32","guid":{"rendered":"http:\/\/municipalidadalhue.cl\/portal\/?p=2180"},"modified":"2014-07-09T16:36:05","modified_gmt":"2014-07-09T16:36:05","slug":"se-celebro-dia-de-bombero-en-alhue","status":"publish","type":"post","link":"https:\/\/municipalidadalhue.cl\/portal\/se-celebro-dia-de-bombero-en-alhue\/","title":{"rendered":"Se celebr\u00f3 D\u00eda del Bombero en Alhu\u00e9"},"content":{"rendered":"<p style=\"text-align: justify;\"><b>Con la participaci\u00f3n de todos los establecimientos educacionales se conmemor\u00f3 desde la Escuela Barrancas de Pichi a esta importante instituci\u00f3n que lleva 15 a\u00f1os trabajando para la comunidad. El Alcalde Roberto Torres Huerta anunci\u00f3 que se aumentar\u00e1n los recursos municipales que se le entregan a esta organizaci\u00f3n no lucrativa.<\/b><\/p>\n<p><a href=\"http:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/06\/DSC04809.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignright size-medium wp-image-2181\" src=\"http:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/06\/DSC04809-300x189.jpg\" alt=\"DSC04809\" width=\"300\" height=\"189\" srcset=\"https:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/06\/DSC04809-300x189.jpg 300w, https:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/06\/DSC04809-1024x648.jpg 1024w, https:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2014\/06\/DSC04809-900x569.jpg 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">El Cuerpo de Bomberos de Villa Alhu\u00e9 es una entidad que siempre se ha destacado por su abnegado trabajo por la comuna, siendo fundamentales en diversas situaciones de emergencia.<\/p>\n<p style=\"text-align: justify;\">Es por esta raz\u00f3n que\u00a0se celebr\u00f3 el D\u00eda del Bombero en Alhu\u00e9, con una serie de presentaciones art\u00edsticas que cautivaron a todos los presentes.<\/p>\n<p style=\"text-align: justify;\">El Alcalde Roberto Torres Huerta fue quien lider\u00f3 a las autoridades asistentes. Adem\u00e1s, estuvieron los concejales, Hugo Lazo, Roberto Aravena, Nancy Cofr\u00e9 y Mario Huerta; el capit\u00e1n del Cuerpo de Bomberos de Villa Alhu\u00e9, Juan Sebasti\u00e1n Cantillana; y el director de la Escuela Barrancas de Pichi, V\u00edctor Cort\u00e9s, entre otros.<\/p>\n<p style=\"text-align: justify;\">Los 5 establecimientos educacionales de nuestra comuna organizaron esta conmemoraci\u00f3n junto al \u00e1rea Extraescolar del DAEM, realizando diferentes presentaciones dedicadas a esta importante instituci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Asimismo, los alumnos de estos recintos participaron de un entretenido concurso de dibujo referente a un nuevo aniversario de Bomberos, en el que fueron premiados los tres primeros lugares, desde pre-kinder hasta 4\u00b0 Medio.<\/p>\n<p style=\"text-align: justify;\">El Alcalde Roberto Torres Huerta destac\u00f3 la labor que realiza esta entidad desde hace 15 a\u00f1os en Alhu\u00e9. \u201cBomberos es una de las pocas instituciones que no recibe una paga por lo que realiza, lo que me parece m\u00e1s que importante, porque exponen sus vidas al servicio de la comunidad\u201d, dijo.<\/p>\n<p style=\"text-align: justify;\">Asimismo, el jefe comunal indic\u00f3 que \u201caumentaremos a $1 mill\u00f3n los recursos que otorgaremos a el Cuerpo de Bomberos de Villa Alhu\u00e9, porque el servicio que prestan es muy relevante para cada uno de los vecinos\u201d.<\/p>\n<p style=\"text-align: justify;\">Por su parte, el capit\u00e1n de Bomberos de nuestra comuna, Juan Sebasti\u00e1n Cantillana, agradeci\u00f3 esta celebraci\u00f3n. \u201cEste es un momento muy importante para nuestra instituci\u00f3n, lo que nos demuestra que la gente se da cuenta de nuestra labor, lo que nos crea un mayor compromiso con la ciudadan\u00eda, para que prestemos un mejor servicio en Alhu\u00e9\u201d, indic\u00f3.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, Cantillana\u00a0se refiri\u00f3 al apoyo econ\u00f3mico que recibir\u00e1n por parte de nuestro municipio. \u201cEl costo de ser Bombero es alt\u00edsimo y que la municipalidad est\u00e9 dispuesta a cooperar nos ayuda a mejorar el servicio, y tambi\u00e9n a poder adquirir nueva implementaci\u00f3n que ir\u00e1 en beneficio de la comunidad\u201d, subray\u00f3.<\/p>\n<p style=\"text-align: justify;\">Finalmente, la concejal Nancy Cofr\u00e9 sostuvo que \u201cquiero entregarle mi reconocimiento a todos los bomberos de la comuna, quienes de forma voluntaria y abnegada entregan su tiempo, su integridad f\u00edsica y sus vidas en muchos momentos para el bien de todos nosotros\u201d.<\/p>\n<p>Vea la galer\u00eda de im\u00e1genes en nuestro facebook:<\/p>\n<p><a href=\"http:\/\/www.facebook.com\/pages\/Ilustre-Municipalidad-de-Alhu%C3%A9\/208816755829101\">http:\/\/www.facebook.com\/pages\/Ilustre-Municipalidad-de-Alhu%C3%A9\/208816755829101<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la participaci\u00f3n de todos los establecimientos educacionales se conmemor\u00f3 desde la Escuela Barrancas de Pichi a esta importante instituci\u00f3n que lleva 15 a\u00f1os trabajando para la comunidad. El Alcalde Roberto Torres Huerta anunci\u00f3 que se aumentar\u00e1n los recursos municipales que se le entregan a esta organizaci\u00f3n no lucrativa. El Cuerpo de Bomberos de Villa Alhu\u00e9 es una entidad que siempre se ha destacado por su abnegado trabajo por la comuna, siendo fundamentales en diversas situaciones de emergencia. Es por esta raz\u00f3n que\u00a0se celebr\u00f3 el D\u00eda del Bombero en Alhu\u00e9,&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,8],"tags":[],"class_list":["post-2180","post","type-post","status-publish","format-standard","hentry","category-comunidad","category-noticia"],"_links":{"self":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/posts\/2180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/comments?post=2180"}],"version-history":[{"count":0,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/posts\/2180\/revisions"}],"wp:attachment":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/media?parent=2180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/categories?post=2180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/tags?post=2180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}