{"id":313,"date":"2013-08-07T22:05:21","date_gmt":"2013-08-07T22:05:21","guid":{"rendered":"http:\/\/municipalidadalhue.cl\/portal\/?p=313"},"modified":"2013-11-19T17:47:17","modified_gmt":"2013-11-19T17:47:17","slug":"con-gran-participacion-se-celebro-dia-nacional-de-la-miel","status":"publish","type":"post","link":"https:\/\/municipalidadalhue.cl\/portal\/con-gran-participacion-se-celebro-dia-nacional-de-la-miel\/","title":{"rendered":"Con gran participaci\u00f3n se celebr\u00f3 D\u00eda Nacional de la Miel"},"content":{"rendered":"<p><b>Por segunda vez consecutiva se conmemor\u00f3 este producto caracter\u00edstico de nuestra comuna. Se realiz\u00f3 una feria expositiva, en donde se dieron a conocer los trabajos que alhu\u00ednos y vecinos de otras comunas de la regi\u00f3n desarrollan con este dulce alimento.<\/b><\/p>\n<p><a href=\"http:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2013\/08\/P8060225.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-314 alignright\" alt=\"P8060225\" src=\"http:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2013\/08\/P8060225-300x221.jpg\" width=\"300\" height=\"221\" srcset=\"https:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2013\/08\/P8060225-300x221.jpg 300w, https:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2013\/08\/P8060225-1024x756.jpg 1024w, https:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2013\/08\/P8060225-900x664.jpg 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>El pasado 6 de agosto se celebr\u00f3 nuevamente en Alhu\u00e9 el D\u00eda Nacional de la Miel, instancia que reuni\u00f3 a importantes autoridades para ser parte de esta conmemoraci\u00f3n que busca que este producto sea insigne de nuestra comuna, destac\u00e1ndose frente a otros que se elaboran en diversas localidades del pa\u00eds.<\/p>\n<p>Entre las autoridades presentes se destac\u00f3 la presencia del alcalde Roberto Torres Huerta; y los concejales Danilo Salazar, Hugo Lazo, Roberto Aravena, Mario Huerta, Luis N\u00fa\u00f1ez y Nancy Cofr\u00e9.<\/p>\n<p>Adem\u00e1s, particip\u00f3 el director Regional de INDAP (Instituto de Desarrollo Agropecuario), Arturo L\u00f3pez; el jefe de \u00e1rea de Melipilla de INDAP, Onofre Sotomayor; el jefe provincial de CONAF (Corporaci\u00f3n Nacional Forestal) Alejandro B\u00f3rquez, as\u00ed como tambi\u00e9n representantes de entidades p\u00fablicas y privadas que prestan sus servicios para nuestra comuna.<\/p>\n<p>Durante esta celebraci\u00f3n diversos apicultores de Alhu\u00e9 y de otras comunas de la Regi\u00f3n Metropolitana se hicieron presentes con stands demostrativos, en los que se pod\u00eda apreciar los diferentes trabajos que realizan con la miel.<\/p>\n<p>El Alcalde Roberto Torres Huerta se mostr\u00f3 muy conforme con el desarrollo de esta celebraci\u00f3n. \u201cEste es el segundo a\u00f1o en que conmemoramos el D\u00eda Nacional de la Miel. En muy pocas partes se celebra este producto, pero nosotros somos una de las comunas privilegiadas a nivel nacional, ya que podemos producir una miel de alt\u00edsima calidad\u201d, destac\u00f3.<\/p>\n<p>Asimismo, la m\u00e1xima autoridad de Alhu\u00e9 agradeci\u00f3 el esfuerzo de los organizadores de esta actividad. \u201cQuiero felicitar a los funcionarios de la Oficina de Desarrollo Local, a la gente de PRODESAL, a los apicultores que participaron de la feria activamente. Los invito a trabajar en conjunto, las puertas del municipio siempre estar\u00e1n abiertas para los productores de miel de la comuna\u201d, indic\u00f3.<\/p>\n<p>En tanto, el director Regional de INDAP, Arturo L\u00f3pez, sostuvo que \u201cla producci\u00f3n de miel en la comuna es muy importante, y nosotros estamos para apoyar a los peque\u00f1os apicultores, m\u00e1s a\u00fan cuando las condiciones clim\u00e1ticas y medioambientales favorecen la producci\u00f3n de este alimento\u201d.<\/p>\n<p>El directivo tambi\u00e9n explic\u00f3 las \u00e1reas en las que INDAP beneficia a los productores de miel de nuestra comuna. \u201cFinanciamos todos los proyectos que nos presentan los peque\u00f1os apicultores, como es aumento de colmenas, construcci\u00f3n de salas de extracci\u00f3n y asesor\u00edas t\u00e9cnicas\u201d, precis\u00f3.<\/p>\n<p>Por su parte, la concejal Nancy Cofr\u00e9 manifest\u00f3 que \u201cesta es una oportunidad para que los alhu\u00ednos demos a conocer a Alhu\u00e9 por medio de un producto tan noble como es la miel. Felicito a los apicultores de la comuna, porque con su trabajo constante han logrado que se celebre este alimento tan importante y sano\u201d.<\/p>\n<p>Algo parecido fue lo que sostuvo el concejal Roberto Aravena. \u201cCon este tipo de actividades se dan a conocer nuestros productos a otros lugares, para que sepan cu\u00e1l es el trabajo de los apicultores de Alhu\u00e9\u201d, acot\u00f3.<\/p>\n<p>Se debe recalcar que se realiz\u00f3 la premiaci\u00f3n del concurso culinario \u201cAlhu\u00e9 con sabor a miel\u201d, competencia que buscaba promover la alimentaci\u00f3n saludable, adem\u00e1s de fomentar la preparaci\u00f3n de platos en base a miel. El primer y tercer lugar lo obtuvo Mar\u00eda Benavides, y el segundo puesto fue para Tanya Camus.<\/p>\n<p>Vea la galer\u00eda de im\u00e1genes en nuestro facebook:<\/p>\n<p><a href=\"http:\/\/www.facebook.com\/pages\/Ilustre-Municipalidad-de-Alhu%C3%A9\/208816755829101\">http:\/\/www.facebook.com\/pages\/Ilustre-Municipalidad-de-Alhu%C3%A9\/208816755829101<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por segunda vez consecutiva se conmemor\u00f3 este producto caracter\u00edstico de nuestra comuna. Se realiz\u00f3 una feria expositiva, en donde se dieron a conocer los trabajos que alhu\u00ednos y vecinos de otras comunas de la regi\u00f3n desarrollan con este dulce alimento. El pasado 6 de agosto se celebr\u00f3 nuevamente en Alhu\u00e9 el D\u00eda Nacional de la Miel, instancia que reuni\u00f3 a importantes autoridades para ser parte de esta conmemoraci\u00f3n que busca que este producto sea insigne de nuestra comuna, destac\u00e1ndose frente a otros que se elaboran en diversas localidades del pa\u00eds.&hellip;<\/p>\n","protected":false},"author":1,"featured_media":314,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,5,7,8],"tags":[],"class_list":["post-313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alcaldesa","category-concejo","category-destacada","category-noticia"],"_links":{"self":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/posts\/313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/comments?post=313"}],"version-history":[{"count":0,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/posts\/313\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/media\/314"}],"wp:attachment":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/media?parent=313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/categories?post=313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/tags?post=313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}