{"id":784,"date":"2013-10-23T20:58:43","date_gmt":"2013-10-23T20:58:43","guid":{"rendered":"http:\/\/municipalidadalhue.cl\/portal\/?p=784"},"modified":"2013-10-24T12:25:46","modified_gmt":"2013-10-24T12:25:46","slug":"consejo-regional-metropolitano-aprobo-por-unanimidad-proyecto-de-luminarias-para-alhue","status":"publish","type":"post","link":"https:\/\/municipalidadalhue.cl\/portal\/consejo-regional-metropolitano-aprobo-por-unanimidad-proyecto-de-luminarias-para-alhue\/","title":{"rendered":"Consejo Regional Metropolitano aprob\u00f3 por unanimidad proyecto de luminarias para Alhu\u00e9"},"content":{"rendered":"<p><b>Se ratific\u00f3 la ejecuci\u00f3n de esta importante iniciativa que permitir\u00e1 pasar de un 46%, a un 100% de cobertura en alumbrado p\u00fablico, por un costo que supera los $1.000 millones.<\/b><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-785 alignright\" alt=\"IMG-20131023-WA000\" src=\"http:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2013\/10\/IMG-20131023-WA000-300x225.jpg\" width=\"300\" height=\"225\" srcset=\"https:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2013\/10\/IMG-20131023-WA000-300x225.jpg 300w, https:\/\/municipalidadalhue.cl\/portal\/wp-content\/uploads\/2013\/10\/IMG-20131023-WA000.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>La falta de alumbrado p\u00fablico en Alhu\u00e9 ha sido un problema que lleva a\u00f1os sin resolver, no obstante, la administraci\u00f3n del Alcalde Roberto Torres Huerta ha trabajado constantemente en mejorar esta situaci\u00f3n, lo que finalmente ser\u00e1 posible tras una serie de gestiones con el Gobierno Regional Metropolitano.<\/p>\n<p>\u201cEl proyecto de ampliaci\u00f3n y reposici\u00f3n de alumbrado p\u00fablico fue aprobado por unanimidad por el Consejo Regional Metropolitano (CORE), quienes ratificaron que nuestra comuna recibir\u00e1 m\u00e1s de $1.000 millones para mejorar y aumentar las luminarias en Alhu\u00e9\u201d, destac\u00f3 el Alcalde Torres.<\/p>\n<p>Esta iniciativa comprende la implementaci\u00f3n y ampliaci\u00f3n del circuito el\u00e9ctrico en toda la comuna. \u201cEsto quiere decir que cada una de las localidades de Alhu\u00e9 contar\u00e1 con luminarias de calidad, mejorando la visibilidad en las noches de veh\u00edculos y peatones, adem\u00e1s de entregar mayor seguridad\u201d, indic\u00f3 la autoridad.<\/p>\n<p>El jefe comunal aprovech\u00f3 de agradecer a los concejales de la comuna, funcionarios municipales, a la gobernadora de Melipilla, Adelaida Mendoza, al Intendente Metropolitano, Jos\u00e9 Antonio Peribonio, y en especial al CORE, por escuchar y responder a esta necesidad hist\u00f3rica de los habitantes de Alhu\u00e9.<\/p>\n<p>Con la aprobaci\u00f3n de este proyecto, nuestra comuna renovar\u00e1 el parque lum\u00ednico existente y adem\u00e1s implementar\u00e1 nueva iluminaci\u00f3n en sectores que no contaban con alumbrado p\u00fablico.<\/p>\n<p>Asimismo, aumentar\u00e1n y mejorar\u00e1n los niveles de iluminaci\u00f3n de calles, pasajes, avenidas y cruces, optimizando el consumo de energ\u00eda el\u00e9ctrica en toda la comuna.<\/p>\n<p>Por su parte, el director SECPLAC, Gonzalo Ar\u00e1nguiz, destac\u00f3 que \u201ccon este proyecto disminuir\u00e1n las fallas en el alumbrado p\u00fablico producidas por actos vand\u00e1licos, o cualquier hecho que pueda deteriorarlas, ya que poseen un sistema que impide el da\u00f1o externo\u201d.<\/p>\n<p>A su vez, el Administrador Municipal, Cristian Le\u00f3n Luna manifest\u00f3 que \u201cesta es una de las tantas iniciativas que la nueva gesti\u00f3n municipal tiene contemplada para mejorar la calidad de vida de la comunidad, con el claro objetivo de construir un futuro digno para las vecinas y vecinos de la comuna de Alhu\u00e9\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se ratific\u00f3 la ejecuci\u00f3n de esta importante iniciativa que permitir\u00e1 pasar de un 46%, a un 100% de cobertura en alumbrado p\u00fablico, por un costo que supera los $1.000 millones. La falta de alumbrado p\u00fablico en Alhu\u00e9 ha sido un problema que lleva a\u00f1os sin resolver, no obstante, la administraci\u00f3n del Alcalde Roberto Torres Huerta ha trabajado constantemente en mejorar esta situaci\u00f3n, lo que finalmente ser\u00e1 posible tras una serie de gestiones con el Gobierno Regional Metropolitano. \u201cEl proyecto de ampliaci\u00f3n y reposici\u00f3n de alumbrado p\u00fablico fue aprobado por unanimidad&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,5,7,8,9],"tags":[],"class_list":["post-784","post","type-post","status-publish","format-standard","hentry","category-alcaldesa","category-concejo","category-destacada","category-noticia","category-proyectos"],"_links":{"self":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/posts\/784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/comments?post=784"}],"version-history":[{"count":0,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/posts\/784\/revisions"}],"wp:attachment":[{"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/media?parent=784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/categories?post=784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/municipalidadalhue.cl\/portal\/wp-json\/wp\/v2\/tags?post=784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}